{"id":314,"count":4,"description":"","link":"https:\/\/www.jowyoriginals.com\/pt-pt\/equipamento-fitness\/treino-forca\/sacos-bulgaros-pt\/","name":"Sacos B\u00falgaros","slug":"sacos-bulgaros-pt","taxonomy":"product_cat","parent":294,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/www.jowyoriginals.com\/pt-pt\/wp-json\/wp\/v2\/product_cat\/314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jowyoriginals.com\/pt-pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.jowyoriginals.com\/pt-pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.jowyoriginals.com\/pt-pt\/wp-json\/wp\/v2\/product_cat\/294"}],"wp:post_type":[{"href":"https:\/\/www.jowyoriginals.com\/pt-pt\/wp-json\/wp\/v2\/product?product_cat=314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}